{"id":1187,"count":2,"description":"The bagpets are <strong>bag holder<\/strong> bone shaped <strong>handmade by Way4dogs<\/strong> To enhance walks with our best friends. You can carry bags, treats, keys, and more inside. This way, walks will be the perfect time of day to unwind and take only the essentials to enjoy the day. It&#039;s the perfect accessory to complete your walking outfit. The hole in the back allows you to remove the bags as often as you need.","link":"https:\/\/elgalgoazul.com\/en\/tienda\/articulos\/bagpet\/","name":"Bagpet","slug":"bagpet","taxonomy":"product_cat","parent":44,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bagpet Portabolsas | El Galgo Azul<\/title>\n<meta name=\"description\" content=\"El accesorio de paseo m\u00e1s pr\u00e1ctico y con m\u00e1s estilo. Encuentra portabolsas con dise\u00f1os preciosos a juego con sus arneses y correas. \u00a1Elige el tuyo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elgalgoazul.com\/en\/tienda\/articulos\/bagpet\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bagpet Portabolsas | El Galgo Azul\" \/>\n<meta property=\"og:description\" content=\"El accesorio de paseo m\u00e1s pr\u00e1ctico y con m\u00e1s estilo. Encuentra portabolsas con dise\u00f1os preciosos a juego con sus arneses y correas. \u00a1Elige el tuyo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elgalgoazul.com\/en\/tienda\/articulos\/bagpet\/\" \/>\n<meta property=\"og:site_name\" content=\"El Galgo Azul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/tienda\\\/articulos\\\/bagpet\\\/\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/tienda\\\/articulos\\\/bagpet\\\/\",\"name\":\"Bagpet Portabolsas | El Galgo Azul\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#website\"},\"description\":\"El accesorio de paseo m\u00e1s pr\u00e1ctico y con m\u00e1s estilo. Encuentra portabolsas con dise\u00f1os preciosos a juego con sus arneses y correas. \u00a1Elige el tuyo!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/tienda\\\/articulos\\\/bagpet\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/tienda\\\/articulos\\\/bagpet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elgalgoazul.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Art\u00edculos para perros\",\"item\":\"https:\\\/\\\/elgalgoazul.com\\\/tienda\\\/articulos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bagpet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#website\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/\",\"name\":\"El Galgo Azul\",\"description\":\"Todo para amantes de los galgos\",\"publisher\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#organization\"},\"alternateName\":\"El Galgo Azul\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elgalgoazul.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#organization\",\"name\":\"El Galgo Azul\",\"alternateName\":\"El Galgo Azul\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Logo-500x500px-1.png\",\"contentUrl\":\"https:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Logo-500x500px-1.png\",\"width\":500,\"height\":500,\"caption\":\"El Galgo Azul\"},\"image\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bagpet Portabolsas | El Galgo Azul","description":"El accesorio de paseo m\u00e1s pr\u00e1ctico y con m\u00e1s estilo. Encuentra portabolsas con dise\u00f1os preciosos a juego con sus arneses y correas. \u00a1Elige el tuyo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elgalgoazul.com\/en\/tienda\/articulos\/bagpet\/","og_locale":"en_GB","og_type":"article","og_title":"Bagpet Portabolsas | El Galgo Azul","og_description":"El accesorio de paseo m\u00e1s pr\u00e1ctico y con m\u00e1s estilo. Encuentra portabolsas con dise\u00f1os preciosos a juego con sus arneses y correas. \u00a1Elige el tuyo!","og_url":"https:\/\/elgalgoazul.com\/en\/tienda\/articulos\/bagpet\/","og_site_name":"El Galgo Azul","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/elgalgoazul.com\/tienda\/articulos\/bagpet\/","url":"https:\/\/elgalgoazul.com\/tienda\/articulos\/bagpet\/","name":"Bagpet Portabolsas | El Galgo Azul","isPartOf":{"@id":"https:\/\/elgalgoazul.com\/#website"},"description":"El accesorio de paseo m\u00e1s pr\u00e1ctico y con m\u00e1s estilo. Encuentra portabolsas con dise\u00f1os preciosos a juego con sus arneses y correas. \u00a1Elige el tuyo!","breadcrumb":{"@id":"https:\/\/elgalgoazul.com\/tienda\/articulos\/bagpet\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/elgalgoazul.com\/tienda\/articulos\/bagpet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elgalgoazul.com\/"},{"@type":"ListItem","position":2,"name":"Art\u00edculos para perros","item":"https:\/\/elgalgoazul.com\/tienda\/articulos\/"},{"@type":"ListItem","position":3,"name":"Bagpet"}]},{"@type":"WebSite","@id":"https:\/\/elgalgoazul.com\/#website","url":"https:\/\/elgalgoazul.com\/","name":"The Blue Greyhound","description":"Everything for greyhound lovers","publisher":{"@id":"https:\/\/elgalgoazul.com\/#organization"},"alternateName":"El Galgo Azul","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elgalgoazul.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/elgalgoazul.com\/#organization","name":"The Blue Greyhound","alternateName":"El Galgo Azul","url":"https:\/\/elgalgoazul.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/elgalgoazul.com\/#\/schema\/logo\/image\/","url":"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2019\/02\/Logo-500x500px-1.png","contentUrl":"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2019\/02\/Logo-500x500px-1.png","width":500,"height":500,"caption":"El Galgo Azul"},"image":{"@id":"https:\/\/elgalgoazul.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/elgalgoazul.com\/en\/wp-json\/wp\/v2\/product_cat\/1187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elgalgoazul.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/elgalgoazul.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/elgalgoazul.com\/en\/wp-json\/wp\/v2\/product_cat\/44"}],"wp:post_type":[{"href":"https:\/\/elgalgoazul.com\/en\/wp-json\/wp\/v2\/product?product_cat=1187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}