{"id":6394,"date":"2017-03-29T08:57:13","date_gmt":"2017-03-29T06:57:13","guid":{"rendered":"https:\/\/elgalgoazul.com\/?p=6394"},"modified":"2021-01-23T19:09:14","modified_gmt":"2021-01-23T18:09:14","slug":"el-galgo-italiano-el-mas-pequeno-de-los-lebreles","status":"publish","type":"post","link":"https:\/\/elgalgoazul.com\/it\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/","title":{"rendered":"Il levriero italiano, il pi\u00f9 piccolo dei levrieri"},"content":{"rendered":"<p><strong>L&#039;eleganza diventa arte con il segugio italiano<\/strong><span style=\"color: #404040; font-family: merriweather, georgia, 'times new roman', serif;\">\u00a0ed \u00e8 che poche razze possono essere orgogliose di essere state l&#039;ispirazione di artisti di tutti i tempi, dalla Grecia classica ai pennelli di grandi uomini del Rinascimento come Giotto. Il suo riflesso nell&#039;arte mostra il<\/span><strong>\u00a0importanza di questo levriero tra l&#039;aristocrazia europea<\/strong><span style=\"color: #404040; font-family: merriweather, georgia, 'times new roman', serif;\">, chi lo ha fatto\u00a0<\/span><strong>la versione pi\u00f9 piccola dei levrieri<\/strong><span style=\"color: #404040; font-family: merriweather, georgia, 'times new roman', serif;\">.<\/span><\/p>\n<p>Nonostante\u00a0<strong>essere sull&#039;orlo dell&#039;estinzione due volte,<\/strong>\u00a0questo piccolo cacciatore \u00e8 un fortunato tra i levrieri.<b>\u00a0<\/b>Il levriero italiano si \u00e8 guadagnato la sopravvivenza nel tempo pi\u00f9 che cacciando lepri, per aver\u00a0<strong>conquistato un buon corner nel triclinio<\/strong>\u00a0(divano romano) per fare un pisolino.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-6401 aligncenter\" src=\"http:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/triclineo-e1490770069817.jpg\" alt=\"piccolo, levriero italiano\" width=\"606\" height=\"429\" srcset=\"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/triclineo-e1490770069817.jpg 1000w, https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/triclineo-e1490770069817-600x424.jpg 600w\" sizes=\"(max-width: 606px) 100vw, 606px\" \/><\/p>\n<h1>ORIGINE E STORIA DEL Levriero ITALIANO<\/h1>\n<p>I pi\u00f9 antichi resti conosciuti di un cane simile all&#039;odierno levriero italiano sono stati trovati in a\u00a0<strong>Tomba egizia di pi\u00f9 di\u00a0<a href=\"https:\/\/www.piccino.net\/piccinoinformation.htm\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=es&amp;q=https:\/\/www.piccino.net\/piccinoinformation.htm&amp;source=gmail&amp;ust=1490707758573000&amp;usg=AFQjCNFxs-s8EsdL7rO5jDTalkGFz_yqLQ\">6.000 anni<\/a>,\u00a0<\/strong>essendo un segno della sua presenza e importanza nella\u00a0<strong>Corte dei Faraoni.\u00a0<\/strong>Anche questo antenato\u00a0<strong>espanso in\u00a0<a href=\"http:\/\/www.fci.be\/Nomenclature\/Standards\/200g10-es.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=es&amp;q=http:\/\/www.fci.be\/Nomenclature\/Standards\/200g10-es.pdf&amp;source=gmail&amp;ust=1490707758573000&amp;usg=AFQjCNF3D6H1ImvCYR-l15TKImyx480aRg\">antica Grecia e Turchia<\/a><\/strong>, essendo rappresentato in varie arti decorative come vasi e vasi.<\/p>\n<p><strong>Il suo arrivo nell&#039;attuale Italia avvenne nel V secolo a.C.\u00a0<\/strong>ed esistono\u00a0<strong>due teorie<\/strong>\u00a0che spiegano come \u00e8 nata.\u00a0<strong>Il primo indica che erano i Fenici<\/strong>\u00a0responsabili della sua introduzione in territorio romano dalla Grecia e dalla Turchia, mentre\u00a0<strong>il secondo ritiene che fossero i soldati romani<\/strong>\u00a0che portavano con s\u00e9 il levriero quando tornavano a casa dopo le campagne militari. Ad ogni modo,\u00a0<strong>divennero i preferiti dei patrizi<\/strong>, che ne svilupp\u00f2 due tipi: uno pi\u00f9 grande per la caccia alla lepre e uno pi\u00f9 piccolo e delicato che divenne un cane da compagnia.<\/p>\n<p>Durante\u00a0<strong>Medioevo<\/strong>\u00a0la gara \u00e8 iniziata\u00a0<strong>espansione nel bacino del Mediterraneo<\/strong>, ma non \u00e8 stato fino a quando<strong>\u00a0Rinascimento<\/strong>\u00a0quando il\u00a0<strong>ulteriore sviluppo della razza come cane da compagnia<\/strong>. Ha raggiunto una tale popolarit\u00e0 tra\u00a0<a href=\"http:\/\/italiangreyhounds.weebly.com\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=es&amp;q=http:\/\/italiangreyhounds.weebly.com\/&amp;source=gmail&amp;ust=1490707758573000&amp;usg=AFQjCNEkZg7SUFK_SeGcut0Dv--omUi_xQ\">il\u00a0<strong>aristocratici italiani<\/strong><\/a>\u00a0durante questo periodo fu all&#039;origine del suo nome &quot;levriero italiano o levriero&quot;, diventando un personaggio comune nei dipinti del Rinascimento italiano.<\/p>\n<p>suo\u00a0<a href=\"https:\/\/www.piccino.net\/piccinoinformation.htm\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=es&amp;q=https:\/\/www.piccino.net\/piccinoinformation.htm&amp;source=gmail&amp;ust=1490707758573000&amp;usg=AFQjCNFxs-s8EsdL7rO5jDTalkGFz_yqLQ\"><strong>ampliamento da parte delle Corti europee<\/strong><\/a>\u00a0ha raggiunto il suo apice nel\u00a0<strong>XVII secolo<\/strong>\u00a0Con l&#039;introduzione della razza in Inghilterra da parte del monarca Carlos I. Grazie a questo, il levriero si \u00e8 affermato nelle corti di Danimarca, Russia, Germania e Prussia, mantenendo sempre il suo profilo di cane da compagnia.<\/p>\n<p>Durante<strong>\u00a0XIX secolo,\u00a0<a href=\"http:\/\/italiangreyhounds.weebly.com\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=es&amp;q=http:\/\/italiangreyhounds.weebly.com\/&amp;source=gmail&amp;ust=1490707758573000&amp;usg=AFQjCNEkZg7SUFK_SeGcut0Dv--omUi_xQ\">la genetica del levriero italiano si \u00e8 impoverita<\/a><\/strong>\u00a0a causa dell&#039;ossessione dei nobili per<strong>\u00a0prendi un cane sempre pi\u00f9 piccolo per differenziarlo dal whippet.\u00a0<\/strong>I levrieri sono diventati cani molto fragili con problemi di fertilit\u00e0 e affetti da\u00a0<strong>nanismo, in piedi<\/strong><strong>\u00a0sull&#039;orlo dell&#039;estinzione<\/strong>. Tuttavia, per<strong>\u00a0all&#039;inizio del XX secolo<\/strong>\u00a0gli allevatori si sono sforzati di\u00a0<strong>recuperare le linee genetiche pi\u00f9 sane della razza<\/strong>.<\/p>\n<p>Ci\u00f2 nonostante,\u00a0<strong>la razza ha affrontato un altro periodo critico<\/strong>\u00a0in cui stava per estinguersi nuovamente a causa della devastazione che era stata\u00a0<strong>le due guerre mondiali in Europa<\/strong>. Fortunatamente il levriero italiano era arrivato negli Stati Uniti e in Canada nel corso del XIX secolo, da dove venivano importati esemplari nel vecchio continente per ripulire e ravvivare le impoverite linee razziali europee.<\/p>\n<p><strong>Oggi, i levrieri italiani mantengono il loro status di cani da compagnia<\/strong>,<strong>\u00a0<\/strong>a differenza di altre razze di levrieri che continuano ad essere sfruttate come cani da caccia o da corsa. Grazie alle loro piccole dimensioni e al carattere estremamente affettuoso, sono diventati\u00a0<strong>uno dei levrieri pi\u00f9 popolari al mondo<\/strong>.<\/p>\n<h1>CARATTERISTICHE FISICHE DEL Levriero ITALIANO<\/h1>\n<p>Lo standard ufficiale per il Levriero Italiano \u00e8 stato stabilito dal\u00a0<strong><a href=\"http:\/\/www.fci.be\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=es&amp;q=http:\/\/www.fci.be\/&amp;source=gmail&amp;ust=1490707758573000&amp;usg=AFQjCNFsgMjyjDFpyFiTxwaXtBA8cI1MXQ\">Federazione cinologica internazionale<\/a>\u00a0nel 2010<\/strong>. Classificato nel gruppo 10 sezione 3 come\u00a0<strong>levrieri a pelo corto<\/strong>, loro\u00a0<a href=\"http:\/\/www.fci.be\/Nomenclature\/Standards\/200g10-es.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=es&amp;q=http:\/\/www.fci.be\/Nomenclature\/Standards\/200g10-es.pdf&amp;source=gmail&amp;ust=1490707758573000&amp;usg=AFQjCNF3D6H1ImvCYR-l15TKImyx480aRg\">caratteristiche fisiche<\/a>\u00a0Sono:<\/p>\n<p><img decoding=\"async\" class=\"wp-image-6397 aligncenter\" src=\"http:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/galgo-itliano-infografia-e1490770313593.jpg\" alt=\"infografica levriero italiano\" width=\"829\" height=\"598\" srcset=\"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/galgo-itliano-infografia-e1490770313593.jpg 1000w, https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/galgo-itliano-infografia-e1490770313593-600x433.jpg 600w\" sizes=\"(max-width: 829px) 100vw, 829px\" \/><\/p>\n<ol>\n<li><strong>Speranza di<\/strong>\u00a0<strong>tutta la vita<\/strong>: tra 12 e 15 anni.<\/li>\n<li><strong>Dimensione<\/strong>: piccolo.<\/li>\n<li><strong>Altezza<\/strong>: tra 32 e 38 cm.<\/li>\n<li><strong>Peso<\/strong>: massimo 5kg.<\/li>\n<li><strong>Carnagione<\/strong>: magro.<\/li>\n<li><strong>Estremit\u00e0<\/strong>: lungo con muscolatura fine.<\/li>\n<li><strong>Occhi<\/strong>: grande, arrotondato ed espressivo con iridi di colore scuro e pigmentazione sul bordo delle palpebre.<\/li>\n<li><strong>Orecchie<\/strong>: alto, piccolo, ripiegato su se stesso e rivolto all&#039;indietro.<\/li>\n<li><strong>Muso:<\/strong>\u00a0stretto con un naso di colore scuro e narici spalancate.<\/li>\n<li><strong>Mascelle<\/strong>: forte e allungato con chiusura a forbice.<\/li>\n<li><strong>Collo<\/strong>: lungo e muscoloso con la linea della gola leggermente convessa e la nuca leggermente arcuata e rigonfia alla base.<\/li>\n<li><strong>Coda<\/strong>: lungo, basso e fine, diritto nella prima met\u00e0 e piega in punta.<\/li>\n<li><strong>Capelli<\/strong>: satinato, fine e liscio.<\/li>\n<li><strong>Colori mantello:\u00a0<\/strong>\n<ul>\n<li>Nero, grigio ed elisabettiano in tutte le sue sfumature.<\/li>\n<li>Qualsiasi delle precedenti con bianco sul davanzale e sui piedi.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<p><strong>Il Greyhound italiano \u00e8 il pi\u00f9 piccolo di tutte le razze di Greyhound<\/strong>, frutto di allevamenti selettivi effettuati negli ultimi secoli. Sono una versione in miniatura delle loro altre razze sorelle, mantenendo le loro caratteristiche fisiche. Per questo motivo i Levrieri Italiani saranno i pi\u00f9 piccoli, ma\u00a0<strong>Sono i pi\u00f9 veloci del resto delle razze di cani di piccola taglia<\/strong>, raggiungendo il\u00a0<strong>40 km all&#039;ora a met\u00e0 gara<\/strong>.<\/p>\n<h1>CARATTERE DEL Levriero ITALIANO<\/h1>\n<p><strong>Il Levriero Italiano \u00e8 un cane tremendamente affettuoso, calmo e riservato.\u00a0<\/strong>Durante la fase del cucciolo, \u00e8 molto felice e attivo, il suo personaggio si rilassa man mano che cresce, ma senza perdere quello spirito da cucciolo giocoso.<\/p>\n<p>\u00c8 una razza molto familiare e familiare, ma\u00a0<strong>tende a creare un legame speciale con un particolare membro della famiglia<\/strong>, al quale chieder\u00e0 la massima attenzione e affetto. Per questa sua caratteristica, da adulto si pu\u00f2 mostrare<strong>\u00a0indifferente e persino timoroso degli estranei<\/strong>, quindi la loro socializzazione non dovrebbe essere trascurata durante il loro sviluppo.<\/p>\n<p>Levrieri Italiani\u00a0<strong>sono cani molto intelligenti e imparano molto velocemente<\/strong>, ma mai attraverso metodi tradizionali che si avvalgono della punizione attiva. \u00c8 importante tenere a mente che i levrieri\u00a0<strong>sono cani molto sensibili<\/strong>\u00a0e possono entrare facilmente<strong>\u00a0impotenza appresa<\/strong>\u00a0se le punizioni sono usate come parte della loro educazione. L&#039;impotenza appresa suppone un blocco per l&#039;animale, che cessa di mostrare comportamenti per paura di essere nuovamente punito.<\/p>\n<p>Nonostante sia stato allevato come cane da compagnia, l&#039;istinto di\u00a0<strong>cacciare piccole prede in movimento\u00a0<\/strong>e le barriere fisiche di solito non sono un impedimento grazie alla sua grande capacit\u00e0 di salto. Poich\u00e9 \u00e8 molto difficile per un cane prestare attenzione al tuo comando quando \u00e8 entrato nell&#039;istinto, devi\u00a0<strong>evita le circostanze che possono attivarlo se lo cammini sciolto<\/strong>.<\/p>\n<p><strong>I levrieri italiani sono cani calmi, ma con un&#039;energia esplosiva<\/strong>\u00a0Sono buoni levrieri, quindi la loro routine di esercizi ideale sarebbe fare una passeggiata di mezz&#039;ora con qualche minuto di corsa. E viste le loro caratteristiche fisiche, lavorano molto bene sui circuiti di agilit\u00e0, dove ottengono ottimi risultati.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-6396 aligncenter\" src=\"http:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/galgo-italiano-despierto-e1490770394614.jpg\" alt=\"\" width=\"522\" height=\"522\" srcset=\"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/galgo-italiano-despierto-e1490770394614.jpg 1000w, https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/galgo-italiano-despierto-e1490770394614-600x600.jpg 600w, https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/galgo-italiano-despierto-e1490770394614-100x100.jpg 100w\" sizes=\"(max-width: 522px) 100vw, 522px\" \/><\/p>\n<h1>MALATTIE DEL Levriero ITALIANO<\/h1>\n<p>Il levriero italiano pu\u00f2 essere affetto da a\u00a0<strong><a href=\"http:\/\/www.akc.org\/dog-breeds\/italian-greyhound\/care\/#health\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=es&amp;q=http:\/\/www.akc.org\/dog-breeds\/italian-greyhound\/care\/%23health&amp;source=gmail&amp;ust=1490707758574000&amp;usg=AFQjCNHPYbvP1ZFmn2Kyb6jADTPT0c4nmQ\">serie di patologie<\/a>\u00a0pi\u00f9 frequenti nel loro gruppo razziale<\/strong>:<\/p>\n<ol>\n<li>Displasia dell&#039;anca.<\/li>\n<li>Lussazione della rotula.<\/li>\n<li>Malattia di Perthes.<\/li>\n<li>Malattia di von Willebrand.<\/li>\n<li>Ipotiroidismo<\/li>\n<li>Allergie<\/li>\n<li>Atrofia retinica progressiva.<\/li>\n<li>Degenerazione del vitreo.<\/li>\n<li>Cascate.<\/li>\n<li>Criptorchidismo.<\/li>\n<li>Epilessia.<\/li>\n<li>Problemi derivati dalla mancanza di densit\u00e0 ossea nei cani di et\u00e0 inferiore ai 18 mesi come fratture, ragadi e lussazioni.<\/li>\n<\/ol>\n<h1>CURA DEL Levriero ITALIANO<\/h1>\n<p>Il levriero italiano\u00a0<strong>non richiede grande cura<\/strong>\u00a0essere un cane a pelo corto. UN\u00a0<strong>igiene di base<\/strong>\u00a0e prenditi cura della salute dei tuoi capelli durante i periodi di caduta.<\/p>\n<p>Questa razza \u00e8 caratterizzata da a\u00a0<strong>crescita molto rapida delle unghie,\u00a0<\/strong>Per questo motivo particolare attenzione deve essere posta alla loro cura per evitare fessurazioni, rotture o deformazioni plantari derivate da una crescita eccessiva. Particolare attenzione deve essere prestata anche alla loro igiene dentale perch\u00e9 sono<strong>\u00a0incline al tartaro<\/strong>.<\/p>\n<p>Come accennato nel punto precedente, \u00e8 necessario prestare particolare attenzione ai levrieri di et\u00e0 inferiore ai 18 mesi a causa di<strong>\u00a0mancanza di densit\u00e0 ossea nello scheletro durante il suo sviluppo<\/strong>. In questa fase si dovrebbe impedire al levriero di giocare con cani che hanno una maggiore forza fisica o con bambini piccoli che ancora non sanno come trattare i cani con cura. Le gambe sono le principali colpite e possono essere rotte con un brutto salto, correndo o con un colpo.<\/p>\n<p>Va inoltre notato che\u00a0<strong>non \u00e8 una razza amica dei climi freddi o piovosi<\/strong>, quindi \u00e8 vivamente consigliato che siano provvisti del necessario riparo, sia in casa che durante le passeggiate: coperte, fornelli, cappotti, pile e impermeabili.<\/p>\n<p>Come con altri cani, deve\u00a0<strong>visita regolarmente il veterinario<\/strong>\u00a0per la vaccinazione, la sverminazione e i controlli sanitari. Dovresti anche mantenere un file\u00a0<strong>routine stabile di passeggiate quotidiane e alimentazione<\/strong>.<\/p>\n<h1>TU E IL TUO Levriero ITALIANO<\/h1>\n<p>Sei uno dei fortunati che condivide il tuo divano con un levriero italiano? Bene, non aspettare oltre per condividere la tua esperienza con noi.\u00a0<strong>Vai avanti e lasciaci un commento raccontandoci la tua storia<\/strong>. Non vediamo l&#039;ora di incontrarla!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6399 aligncenter\" src=\"http:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/galgo-italiano-copy-e1490770466500.jpg\" alt=\"\" width=\"554\" height=\"554\" srcset=\"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/galgo-italiano-copy-e1490770466500.jpg 1000w, https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/galgo-italiano-copy-e1490770466500-600x600.jpg 600w, https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/galgo-italiano-copy-e1490770466500-100x100.jpg 100w\" sizes=\"(max-width: 554px) 100vw, 554px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Con il levriero italiano l&#039;eleganza diventa arte e poche razze possono vantarsi di aver ispirato artisti di tutti i tempi, dalla Grecia classica ai pennelli dei grandi artisti del Rinascimento come Giotto. La sua riflessione nell&#039;arte mostra l&#039;importanza di questo levriero presso l&#039;aristocrazia europea, che lo convert\u00ec... <a title=\"Il levriero italiano, il pi\u00f9 piccolo dei levrieri\" class=\"read-more\" href=\"https:\/\/elgalgoazul.com\/it\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/\" aria-label=\"Per saperne di pi\u00f9 su Il Piccolo Levriero Italiano, il pi\u00f9 piccolo dei levrieri\">Leggi tutto<\/a><\/p>","protected":false},"author":1,"featured_media":6401,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[221],"tags":[264,266,267,260,261,47,310,63,262,312,315,220,311,253,263,314,254,64,313,265,316,268,187],"class_list":["post-6394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tipos-de-galgos","tag-caracteristicas","tag-cuidados","tag-enfermedades","tag-fci","tag-federacion-cinologica-internacional","tag-galgo","tag-galgo-italiano","tag-galgos","tag-historia","tag-ig","tag-italia","tag-lebrel","tag-lebrel-italiano","tag-lebreles","tag-origen","tag-pequeno","tag-perro","tag-perros","tag-piccolo-levriero-italiano","tag-razas","tag-renacimiento","tag-salud","tag-whippet"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Galgo Italiano, el m\u00e1s peque\u00f1o de los lebreles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elgalgoazul.com\/it\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Galgo Italiano, el m\u00e1s peque\u00f1o de los lebreles\" \/>\n<meta property=\"og:description\" content=\"La elegancia se hizo arte con el lebrel italiano\u00a0y es que pocas razas pueden enorgullecerse de haber sido la inspiraci\u00f3n de artistas de todos los tiempos, desde la Grecia Cl\u00e1sica hasta los pinceles de grandes renacentistas como Giotto. Su reflejo en el arte muestra la\u00a0importancia de este galgo entre la aristocracia europea, quienes lo convirtieron ... Leggi tutto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elgalgoazul.com\/it\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/\" \/>\n<meta property=\"og:site_name\" content=\"El Galgo Azul\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-29T06:57:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-23T18:09:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/triclineo-e1490770069817.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elgalgoazul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"elgalgoazul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\\\/\"},\"author\":{\"name\":\"elgalgoazul\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#\\\/schema\\\/person\\\/2b66084e44ab89f353fc21caa31c08e0\"},\"headline\":\"El Galgo Italiano, el m\u00e1s peque\u00f1o de los lebreles\",\"datePublished\":\"2017-03-29T06:57:13+00:00\",\"dateModified\":\"2021-01-23T18:09:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\\\/\"},\"wordCount\":1657,\"publisher\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/triclineo-e1490770069817.jpg\",\"keywords\":[\"caracter\u00edsticas\",\"cuidados\",\"enfermedades\",\"FCI\",\"Federaci\u00f3n Cinol\u00f3gica Internacional\",\"galgo\",\"galgo italiano\",\"galgos\",\"historia\",\"IG\",\"Italia\",\"lebrel\",\"lebrel italiano\",\"lebreles\",\"origen\",\"peque\u00f1o\",\"perro\",\"perros\",\"Piccolo Levriero Italiano\",\"razas\",\"Renacimiento\",\"salud\",\"whippet\"],\"articleSection\":[\"Tipos de galgos\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\\\/\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\\\/\",\"name\":\"El Galgo Italiano, el m\u00e1s peque\u00f1o de los lebreles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/triclineo-e1490770069817.jpg\",\"datePublished\":\"2017-03-29T06:57:13+00:00\",\"dateModified\":\"2021-01-23T18:09:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elgalgoazul.com\\\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/triclineo-e1490770069817.jpg\",\"contentUrl\":\"https:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/triclineo-e1490770069817.jpg\",\"width\":1000,\"height\":707,\"caption\":\"piccolo, lebrel italiano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elgalgoazul.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Galgo Italiano, el m\u00e1s peque\u00f1o de los lebreles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#website\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/\",\"name\":\"El Galgo Azul\",\"description\":\"Todo para amantes de los galgos\",\"publisher\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#organization\"},\"alternateName\":\"El Galgo Azul\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elgalgoazul.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#organization\",\"name\":\"El Galgo Azul\",\"alternateName\":\"El Galgo Azul\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Logo-500x500px-1.png\",\"contentUrl\":\"https:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Logo-500x500px-1.png\",\"width\":500,\"height\":500,\"caption\":\"El Galgo Azul\"},\"image\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#\\\/schema\\\/person\\\/2b66084e44ab89f353fc21caa31c08e0\",\"name\":\"elgalgoazul\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il levriero italiano, il pi\u00f9 piccolo dei levrieri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elgalgoazul.com\/it\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/","og_locale":"it_IT","og_type":"article","og_title":"El Galgo Italiano, el m\u00e1s peque\u00f1o de los lebreles","og_description":"La elegancia se hizo arte con el lebrel italiano\u00a0y es que pocas razas pueden enorgullecerse de haber sido la inspiraci\u00f3n de artistas de todos los tiempos, desde la Grecia Cl\u00e1sica hasta los pinceles de grandes renacentistas como Giotto. Su reflejo en el arte muestra la\u00a0importancia de este galgo entre la aristocracia europea, quienes lo convirtieron ... Leggi tutto","og_url":"https:\/\/elgalgoazul.com\/it\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/","og_site_name":"El Galgo Azul","article_published_time":"2017-03-29T06:57:13+00:00","article_modified_time":"2021-01-23T18:09:14+00:00","og_image":[{"width":1000,"height":707,"url":"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/triclineo-e1490770069817.jpg","type":"image\/jpeg"}],"author":"elgalgoazul","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"elgalgoazul","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elgalgoazul.com\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/#article","isPartOf":{"@id":"https:\/\/elgalgoazul.com\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/"},"author":{"name":"elgalgoazul","@id":"https:\/\/elgalgoazul.com\/#\/schema\/person\/2b66084e44ab89f353fc21caa31c08e0"},"headline":"El Galgo Italiano, el m\u00e1s peque\u00f1o de los lebreles","datePublished":"2017-03-29T06:57:13+00:00","dateModified":"2021-01-23T18:09:14+00:00","mainEntityOfPage":{"@id":"https:\/\/elgalgoazul.com\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/"},"wordCount":1657,"publisher":{"@id":"https:\/\/elgalgoazul.com\/#organization"},"image":{"@id":"https:\/\/elgalgoazul.com\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/#primaryimage"},"thumbnailUrl":"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/triclineo-e1490770069817.jpg","keywords":["caracter\u00edsticas","cuidados","enfermedades","FCI","Federaci\u00f3n Cinol\u00f3gica Internacional","galgo","galgo italiano","galgos","historia","IG","Italia","lebrel","lebrel italiano","lebreles","origen","peque\u00f1o","perro","perros","Piccolo Levriero Italiano","razas","Renacimiento","salud","whippet"],"articleSection":["Tipos de galgos"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/elgalgoazul.com\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/","url":"https:\/\/elgalgoazul.com\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/","name":"Il levriero italiano, il pi\u00f9 piccolo dei levrieri","isPartOf":{"@id":"https:\/\/elgalgoazul.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elgalgoazul.com\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/#primaryimage"},"image":{"@id":"https:\/\/elgalgoazul.com\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/#primaryimage"},"thumbnailUrl":"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/triclineo-e1490770069817.jpg","datePublished":"2017-03-29T06:57:13+00:00","dateModified":"2021-01-23T18:09:14+00:00","breadcrumb":{"@id":"https:\/\/elgalgoazul.com\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elgalgoazul.com\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/elgalgoazul.com\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/#primaryimage","url":"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/triclineo-e1490770069817.jpg","contentUrl":"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2017\/03\/triclineo-e1490770069817.jpg","width":1000,"height":707,"caption":"piccolo, lebrel italiano"},{"@type":"BreadcrumbList","@id":"https:\/\/elgalgoazul.com\/el-galgo-italiano-el-mas-pequeno-de-los-lebreles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elgalgoazul.com\/"},{"@type":"ListItem","position":2,"name":"El Galgo Italiano, el m\u00e1s peque\u00f1o de los lebreles"}]},{"@type":"WebSite","@id":"https:\/\/elgalgoazul.com\/#website","url":"https:\/\/elgalgoazul.com\/","name":"Il levriero blu","description":"Tutto per gli amanti dei levrieri","publisher":{"@id":"https:\/\/elgalgoazul.com\/#organization"},"alternateName":"El Galgo Azul","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elgalgoazul.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/elgalgoazul.com\/#organization","name":"Il levriero blu","alternateName":"El Galgo Azul","url":"https:\/\/elgalgoazul.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/elgalgoazul.com\/#\/schema\/logo\/image\/","url":"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2019\/02\/Logo-500x500px-1.png","contentUrl":"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2019\/02\/Logo-500x500px-1.png","width":500,"height":500,"caption":"El Galgo Azul"},"image":{"@id":"https:\/\/elgalgoazul.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elgalgoazul.com\/#\/schema\/person\/2b66084e44ab89f353fc21caa31c08e0","name":"elgalgoazul"}]}},"_links":{"self":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/posts\/6394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/comments?post=6394"}],"version-history":[{"count":0,"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/posts\/6394\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/media\/6401"}],"wp:attachment":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/media?parent=6394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/categories?post=6394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/tags?post=6394"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}