{"id":51954,"date":"2025-03-20T10:00:20","date_gmt":"2025-03-20T09:00:20","guid":{"rendered":"https:\/\/elgalgoazul.com\/?post_type=product&#038;p=51954"},"modified":"2026-04-29T09:09:48","modified_gmt":"2026-04-29T07:09:48","slug":"collar-personalizado-lavanda","status":"publish","type":"product","link":"https:\/\/elgalgoazul.com\/it\/comprar\/collar-personalizado-lavanda\/","title":{"rendered":"Collana lilla personalizzata"},"content":{"rendered":"<p>Hai il coraggio di comprare alla cieca? Stiamo lanciando la nostra nuova collezione primaverile Caral\u00e1piz Block senza mostrarla... vi diamo solo due indizi: \u00e8 una versione della nostra storica Caral\u00e1piz e i colori in cui \u00e8 disponibile sono quelli che vedete nella foto. Edizione limitata.<\/p>\n<p>Collana di identificazione personalizzata con nome e numero di telefono. \u00c8 un collare a scatto leggero in modo da poterlo abbinare all&#039;imbracatura o al collare, ed \u00e8 sempre identificato.<\/p>\n<p>In caso di domande, non esitare a\u00a0<a href=\"https:\/\/elgalgoazul.com\/it\/contacto\/\">contatto<\/a>\u00a0con noi.<\/p>\n<p>Tempo di consegna stimato da 7 a 15 giorni.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfTe atreves a comprar a ciegas? Lanzamos nuestra nueva colecci\u00f3n Caral\u00e1piz Block Spring sin mostrala&#8230; solo te damos 2 pistas: es una versi\u00f3n de nuestro hist\u00f3rico Caral\u00e1piz y los colores que lleva son los que ves en la foto. Edici\u00f3n limitada. Collar identificativo personalizado con nombre y tel\u00e9fono. Es un collar click ligero para que &#8230; <a title=\"Collana lilla personalizzata\" class=\"read-more\" href=\"https:\/\/elgalgoazul.com\/it\/comprar\/collar-personalizado-lavanda\/\" aria-label=\"Per saperne di pi\u00f9 su Collar personalizado lila\">Leggi tutto<\/a><\/p>","protected":false},"featured_media":52064,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[1274,643],"product_tag":[1345],"class_list":["post-51954","product","type-product","status-publish","has-post-thumbnail","product_cat-collares-identificativos","product_cat-identificacion","product_tag-caralapiz","product_shipping_class-restodeproductos","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Collar personalizado lila - El Galgo Azul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elgalgoazul.com\/it\/comprar\/collar-personalizado-lavanda\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Collar personalizado lila - El Galgo Azul\" \/>\n<meta property=\"og:description\" content=\"\u00bfTe atreves a comprar a ciegas? Lanzamos nuestra nueva colecci\u00f3n Caral\u00e1piz Block Spring sin mostrala&#8230; solo te damos 2 pistas: es una versi\u00f3n de nuestro hist\u00f3rico Caral\u00e1piz y los colores que lleva son los que ves en la foto. Edici\u00f3n limitada. Collar identificativo personalizado con nombre y tel\u00e9fono. Es un collar click ligero para que ... Leggi tutto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elgalgoazul.com\/it\/comprar\/collar-personalizado-lavanda\/\" \/>\n<meta property=\"og:site_name\" content=\"El Galgo Azul\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T07:09:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2025\/04\/id-lavanda-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/comprar\\\/collar-personalizado-lavanda\\\/\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/comprar\\\/collar-personalizado-lavanda\\\/\",\"name\":\"Collar personalizado lila - El Galgo Azul\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/comprar\\\/collar-personalizado-lavanda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/comprar\\\/collar-personalizado-lavanda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/id-lavanda-scaled.jpg\",\"datePublished\":\"2025-03-20T09:00:20+00:00\",\"dateModified\":\"2026-04-29T07:09:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/comprar\\\/collar-personalizado-lavanda\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elgalgoazul.com\\\/comprar\\\/collar-personalizado-lavanda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/comprar\\\/collar-personalizado-lavanda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/id-lavanda-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/id-lavanda-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/comprar\\\/collar-personalizado-lavanda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elgalgoazul.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/elgalgoazul.com\\\/fr\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Collar personalizado lila\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#website\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/\",\"name\":\"El Galgo Azul\",\"description\":\"Todo para amantes de los galgos\",\"publisher\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#organization\"},\"alternateName\":\"El Galgo Azul\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elgalgoazul.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#organization\",\"name\":\"El Galgo Azul\",\"alternateName\":\"El Galgo Azul\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Logo-500x500px-1.png\",\"contentUrl\":\"http:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Logo-500x500px-1.png\",\"width\":500,\"height\":500,\"caption\":\"El Galgo Azul\"},\"image\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Collare lilla personalizzato - Il levriero blu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elgalgoazul.com\/it\/comprar\/collar-personalizado-lavanda\/","og_locale":"it_IT","og_type":"article","og_title":"Collar personalizado lila - El Galgo Azul","og_description":"\u00bfTe atreves a comprar a ciegas? Lanzamos nuestra nueva colecci\u00f3n Caral\u00e1piz Block Spring sin mostrala&#8230; solo te damos 2 pistas: es una versi\u00f3n de nuestro hist\u00f3rico Caral\u00e1piz y los colores que lleva son los que ves en la foto. Edici\u00f3n limitada. Collar identificativo personalizado con nombre y tel\u00e9fono. Es un collar click ligero para que ... Leggi tutto","og_url":"https:\/\/elgalgoazul.com\/it\/comprar\/collar-personalizado-lavanda\/","og_site_name":"El Galgo Azul","article_modified_time":"2026-04-29T07:09:48+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2025\/04\/id-lavanda-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elgalgoazul.com\/comprar\/collar-personalizado-lavanda\/","url":"https:\/\/elgalgoazul.com\/comprar\/collar-personalizado-lavanda\/","name":"Collare lilla personalizzato - Il levriero blu","isPartOf":{"@id":"https:\/\/elgalgoazul.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elgalgoazul.com\/comprar\/collar-personalizado-lavanda\/#primaryimage"},"image":{"@id":"https:\/\/elgalgoazul.com\/comprar\/collar-personalizado-lavanda\/#primaryimage"},"thumbnailUrl":"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2025\/04\/id-lavanda-scaled.jpg","datePublished":"2025-03-20T09:00:20+00:00","dateModified":"2026-04-29T07:09:48+00:00","breadcrumb":{"@id":"https:\/\/elgalgoazul.com\/comprar\/collar-personalizado-lavanda\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elgalgoazul.com\/comprar\/collar-personalizado-lavanda\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/elgalgoazul.com\/comprar\/collar-personalizado-lavanda\/#primaryimage","url":"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2025\/04\/id-lavanda-scaled.jpg","contentUrl":"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2025\/04\/id-lavanda-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/elgalgoazul.com\/comprar\/collar-personalizado-lavanda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elgalgoazul.com\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/elgalgoazul.com\/fr\/tienda\/"},{"@type":"ListItem","position":3,"name":"Collar personalizado lila"}]},{"@type":"WebSite","@id":"https:\/\/elgalgoazul.com\/#website","url":"https:\/\/elgalgoazul.com\/","name":"Il levriero blu","description":"Tutto per gli amanti dei levrieri","publisher":{"@id":"https:\/\/elgalgoazul.com\/#organization"},"alternateName":"El Galgo Azul","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elgalgoazul.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/elgalgoazul.com\/#organization","name":"Il levriero blu","alternateName":"El Galgo Azul","url":"https:\/\/elgalgoazul.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/elgalgoazul.com\/#\/schema\/logo\/image\/","url":"http:\/\/elgalgoazul.com\/wp-content\/uploads\/2019\/02\/Logo-500x500px-1.png","contentUrl":"http:\/\/elgalgoazul.com\/wp-content\/uploads\/2019\/02\/Logo-500x500px-1.png","width":500,"height":500,"caption":"El Galgo Azul"},"image":{"@id":"https:\/\/elgalgoazul.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/product\/51954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/comments?post=51954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/media\/52064"}],"wp:attachment":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/media?parent=51954"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/product_brand?post=51954"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/product_cat?post=51954"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/product_tag?post=51954"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}