{"id":1273,"count":7,"description":"Sopra <strong>Il levriero blu<\/strong> ci piace che i nostri cani<strong> essere sempre al sicuro, identificati e a proprio agio prima di tutto<\/strong>. I nostri<strong> targhette di identificazione<\/strong> para perros est\u00e1n preparadas para ser grabadas y salvaros a ambos\u00a0de un susto inesperado.\r\n\r\nSiempre con toda la ergonom\u00eda pensada para los peludos y hechas con mucho amor perruno. Una de las formas que tenemos de <strong>metti un tocco di identit\u00e0<\/strong> ai nostri amici cani.","link":"https:\/\/elgalgoazul.com\/it\/tienda\/articulos\/identificacion\/placas-identificativas\/","name":"Targhe di identificazione","slug":"placas-identificativas","taxonomy":"product_cat","parent":643,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Placa Identificativa para Perros | El Galgo Azul<\/title>\n<meta name=\"description\" content=\"La forma m\u00e1s segura de llevarte siempre de vuelta a casa. Descubre placas identificativas para perros con grabados duraderos y dise\u00f1os llenos de amor. \u00a1Entra!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elgalgoazul.com\/it\/tienda\/articulos\/identificacion\/placas-identificativas\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Placa Identificativa para Perros | El Galgo Azul\" \/>\n<meta property=\"og:description\" content=\"La forma m\u00e1s segura de llevarte siempre de vuelta a casa. Descubre placas identificativas para perros con grabados duraderos y dise\u00f1os llenos de amor. \u00a1Entra!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elgalgoazul.com\/it\/tienda\/articulos\/identificacion\/placas-identificativas\/\" \/>\n<meta property=\"og:site_name\" content=\"El Galgo Azul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/tienda\\\/articulos\\\/identificacion\\\/placas-identificativas\\\/\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/tienda\\\/articulos\\\/identificacion\\\/placas-identificativas\\\/\",\"name\":\"Placa Identificativa para Perros | El Galgo Azul\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#website\"},\"description\":\"La forma m\u00e1s segura de llevarte siempre de vuelta a casa. Descubre placas identificativas para perros con grabados duraderos y dise\u00f1os llenos de amor. \u00a1Entra!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/tienda\\\/articulos\\\/identificacion\\\/placas-identificativas\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/tienda\\\/articulos\\\/identificacion\\\/placas-identificativas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elgalgoazul.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Art\u00edculos para perros\",\"item\":\"https:\\\/\\\/elgalgoazul.com\\\/tienda\\\/articulos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Identificaci\u00f3n\",\"item\":\"https:\\\/\\\/elgalgoazul.com\\\/tienda\\\/articulos\\\/identificacion\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Placas Identificativas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#website\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/\",\"name\":\"El Galgo Azul\",\"description\":\"Todo para amantes de los galgos\",\"publisher\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#organization\"},\"alternateName\":\"El Galgo Azul\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elgalgoazul.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#organization\",\"name\":\"El Galgo Azul\",\"alternateName\":\"El Galgo Azul\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Logo-500x500px-1.png\",\"contentUrl\":\"https:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Logo-500x500px-1.png\",\"width\":500,\"height\":500,\"caption\":\"El Galgo Azul\"},\"image\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Placa Identificativa para Perros | El Galgo Azul","description":"La forma m\u00e1s segura de llevarte siempre de vuelta a casa. Descubre placas identificativas para perros con grabados duraderos y dise\u00f1os llenos de amor. \u00a1Entra!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elgalgoazul.com\/it\/tienda\/articulos\/identificacion\/placas-identificativas\/","og_locale":"it_IT","og_type":"article","og_title":"Placa Identificativa para Perros | El Galgo Azul","og_description":"La forma m\u00e1s segura de llevarte siempre de vuelta a casa. Descubre placas identificativas para perros con grabados duraderos y dise\u00f1os llenos de amor. \u00a1Entra!","og_url":"https:\/\/elgalgoazul.com\/it\/tienda\/articulos\/identificacion\/placas-identificativas\/","og_site_name":"El Galgo Azul","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/elgalgoazul.com\/tienda\/articulos\/identificacion\/placas-identificativas\/","url":"https:\/\/elgalgoazul.com\/tienda\/articulos\/identificacion\/placas-identificativas\/","name":"Placa Identificativa para Perros | El Galgo Azul","isPartOf":{"@id":"https:\/\/elgalgoazul.com\/#website"},"description":"La forma m\u00e1s segura de llevarte siempre de vuelta a casa. Descubre placas identificativas para perros con grabados duraderos y dise\u00f1os llenos de amor. \u00a1Entra!","breadcrumb":{"@id":"https:\/\/elgalgoazul.com\/tienda\/articulos\/identificacion\/placas-identificativas\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/elgalgoazul.com\/tienda\/articulos\/identificacion\/placas-identificativas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elgalgoazul.com\/"},{"@type":"ListItem","position":2,"name":"Art\u00edculos para perros","item":"https:\/\/elgalgoazul.com\/tienda\/articulos\/"},{"@type":"ListItem","position":3,"name":"Identificaci\u00f3n","item":"https:\/\/elgalgoazul.com\/tienda\/articulos\/identificacion\/"},{"@type":"ListItem","position":4,"name":"Placas Identificativas"}]},{"@type":"WebSite","@id":"https:\/\/elgalgoazul.com\/#website","url":"https:\/\/elgalgoazul.com\/","name":"Il levriero blu","description":"Tutto per gli amanti dei levrieri","publisher":{"@id":"https:\/\/elgalgoazul.com\/#organization"},"alternateName":"El Galgo Azul","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elgalgoazul.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/elgalgoazul.com\/#organization","name":"Il levriero blu","alternateName":"El Galgo Azul","url":"https:\/\/elgalgoazul.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/elgalgoazul.com\/#\/schema\/logo\/image\/","url":"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2019\/02\/Logo-500x500px-1.png","contentUrl":"https:\/\/elgalgoazul.com\/wp-content\/uploads\/2019\/02\/Logo-500x500px-1.png","width":500,"height":500,"caption":"El Galgo Azul"},"image":{"@id":"https:\/\/elgalgoazul.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/product_cat\/1273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/product_cat\/643"}],"wp:post_type":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/product?product_cat=1273"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}