{"id":662,"count":23,"description":"Chi di noi condivide la vita con i levrieri sa che sono cani molto freddi, ecco perch\u00e9 abbiamo deciso di lanciare una collezione di <strong>vestiti per levrieri e altri cani<\/strong>. Tutti i <strong>Blue Greyhound Dog Clothes<\/strong> \u00c8 fatto su misura e con grande cura, perch\u00e9 sappiamo che meritano tutto e perch\u00e9 vogliamo che stiano bene a casa e per strada.","link":"https:\/\/elgalgoazul.com\/it\/tienda\/ropa-para-galgo\/","name":"Abbigliamento da levriero","slug":"ropa-para-galgo","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Categor\u00eda de Ropa para galgo - El Galgo Azul<\/title>\n<meta name=\"description\" content=\"Los que compartimos vida con galgos sabemos que son perros muy frioleros, por eso nos decidimos a lanzar una colecci\u00f3n de ropa para galgos y otros perros.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elgalgoazul.com\/it\/tienda\/ropa-para-galgo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Categor\u00eda de Ropa para galgo - El Galgo Azul\" \/>\n<meta property=\"og:description\" content=\"Los que compartimos vida con galgos sabemos que son perros muy frioleros, por eso nos decidimos a lanzar una colecci\u00f3n de ropa para galgos y otros perros.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elgalgoazul.com\/it\/tienda\/ropa-para-galgo\/\" \/>\n<meta property=\"og:site_name\" content=\"El Galgo Azul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/tienda\\\/ropa-para-galgo\\\/\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/tienda\\\/ropa-para-galgo\\\/\",\"name\":\"Categor\u00eda de Ropa para galgo - El Galgo Azul\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#website\"},\"description\":\"Los que compartimos vida con galgos sabemos que son perros muy frioleros, por eso nos decidimos a lanzar una colecci\u00f3n de ropa para galgos y otros perros.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/tienda\\\/ropa-para-galgo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/tienda\\\/ropa-para-galgo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elgalgoazul.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ropa para galgo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#website\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/\",\"name\":\"El Galgo Azul\",\"description\":\"Todo para amantes de los galgos\",\"publisher\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#organization\"},\"alternateName\":\"El Galgo Azul\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elgalgoazul.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#organization\",\"name\":\"El Galgo Azul\",\"alternateName\":\"El Galgo Azul\",\"url\":\"https:\\\/\\\/elgalgoazul.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Logo-500x500px-1.png\",\"contentUrl\":\"http:\\\/\\\/elgalgoazul.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Logo-500x500px-1.png\",\"width\":500,\"height\":500,\"caption\":\"El Galgo Azul\"},\"image\":{\"@id\":\"https:\\\/\\\/elgalgoazul.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Greyhound Abbigliamento Categoria - El Galgo Azul","description":"Quelli di noi che condividono la vita con i levrieri sanno che sono cani molto freddi, quindi abbiamo deciso di lanciare una collezione di abbigliamento per levrieri e altri cani.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elgalgoazul.com\/it\/tienda\/ropa-para-galgo\/","og_locale":"it_IT","og_type":"article","og_title":"Categor\u00eda de Ropa para galgo - El Galgo Azul","og_description":"Los que compartimos vida con galgos sabemos que son perros muy frioleros, por eso nos decidimos a lanzar una colecci\u00f3n de ropa para galgos y otros perros.","og_url":"https:\/\/elgalgoazul.com\/it\/tienda\/ropa-para-galgo\/","og_site_name":"El Galgo Azul","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/elgalgoazul.com\/tienda\/ropa-para-galgo\/","url":"https:\/\/elgalgoazul.com\/tienda\/ropa-para-galgo\/","name":"Greyhound Abbigliamento Categoria - El Galgo Azul","isPartOf":{"@id":"https:\/\/elgalgoazul.com\/#website"},"description":"Quelli di noi che condividono la vita con i levrieri sanno che sono cani molto freddi, quindi abbiamo deciso di lanciare una collezione di abbigliamento per levrieri e altri cani.","breadcrumb":{"@id":"https:\/\/elgalgoazul.com\/tienda\/ropa-para-galgo\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/elgalgoazul.com\/tienda\/ropa-para-galgo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elgalgoazul.com\/"},{"@type":"ListItem","position":2,"name":"Ropa para galgo"}]},{"@type":"WebSite","@id":"https:\/\/elgalgoazul.com\/#website","url":"https:\/\/elgalgoazul.com\/","name":"Il levriero blu","description":"Tutto per gli amanti dei levrieri","publisher":{"@id":"https:\/\/elgalgoazul.com\/#organization"},"alternateName":"El Galgo Azul","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elgalgoazul.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/elgalgoazul.com\/#organization","name":"Il levriero blu","alternateName":"El Galgo Azul","url":"https:\/\/elgalgoazul.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/elgalgoazul.com\/#\/schema\/logo\/image\/","url":"http:\/\/elgalgoazul.com\/wp-content\/uploads\/2019\/02\/Logo-500x500px-1.png","contentUrl":"http:\/\/elgalgoazul.com\/wp-content\/uploads\/2019\/02\/Logo-500x500px-1.png","width":500,"height":500,"caption":"El Galgo Azul"},"image":{"@id":"https:\/\/elgalgoazul.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/product_cat\/662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/elgalgoazul.com\/it\/wp-json\/wp\/v2\/product?product_cat=662"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}